{"id":125597,"date":"2023-11-22T15:09:57","date_gmt":"2023-11-22T14:09:57","guid":{"rendered":"https:\/\/www.bontempi.it\/designer\/studio-fb-design\/"},"modified":"2026-04-07T16:44:12","modified_gmt":"2026-04-07T14:44:12","slug":"studio-fb-design","status":"publish","type":"designer","link":"https:\/\/www.bontempi.it\/fr\/designer\/studio-f-b-design\/","title":{"rendered":"Studio F+B Design"},"content":{"rendered":"<p>StudioF + B Design, d&rsquo;Oriano et Beatrice Favaretto, est n\u00e9 de la volont\u00e9 d\u2019unir diff\u00e9rentes disciplines et exp\u00e9riences artistiques en cr\u00e9ant un dialogue entre l&rsquo;image et le produit.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le studio se concentre sur la cr\u00e9ation d&rsquo;accessoires d&rsquo;ameublement et d&rsquo;\u00e9clairage pour de nombreuses marques internationales, ainsi que sur la production d&rsquo;images anim\u00e9es et d&rsquo;installations vid\u00e9o. Leur approche est simple envers les mat\u00e9riaux et leur forme et se caract\u00e9rise par une ironie ludique, donnant naissance \u00e0 des objets intrigants dans une combinaison parfaite entre contenu et forme fonction. Les objets deviennent ainsi complices de notre habitat, pour nous \u00e9merveiller avec la m\u00eame intensit\u00e9 au fil du temps.<\/p>\n","protected":false},"featured_media":162128,"template":"","class_list":["post-125597","designer","type-designer","status-publish","has-post-thumbnail","hentry"],"acf":{"gallery":[46417,46420,46423,8337,8341,8345,8350,46428,8358]},"_links":{"self":[{"href":"https:\/\/www.bontempi.it\/fr\/wp-json\/wp\/v2\/designer\/125597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bontempi.it\/fr\/wp-json\/wp\/v2\/designer"}],"about":[{"href":"https:\/\/www.bontempi.it\/fr\/wp-json\/wp\/v2\/types\/designer"}],"acf:attachment":[{"embeddable":true,"href":"https:\/\/www.bontempi.it\/fr\/wp-json\/wp\/v2\/media\/8358"},{"embeddable":true,"href":"https:\/\/www.bontempi.it\/fr\/wp-json\/wp\/v2\/media\/46428"},{"embeddable":true,"href":"https:\/\/www.bontempi.it\/fr\/wp-json\/wp\/v2\/media\/8350"},{"embeddable":true,"href":"https:\/\/www.bontempi.it\/fr\/wp-json\/wp\/v2\/media\/8345"},{"embeddable":true,"href":"https:\/\/www.bontempi.it\/fr\/wp-json\/wp\/v2\/media\/8341"},{"embeddable":true,"href":"https:\/\/www.bontempi.it\/fr\/wp-json\/wp\/v2\/media\/8337"},{"embeddable":true,"href":"https:\/\/www.bontempi.it\/fr\/wp-json\/wp\/v2\/media\/46423"},{"embeddable":true,"href":"https:\/\/www.bontempi.it\/fr\/wp-json\/wp\/v2\/media\/46420"},{"embeddable":true,"href":"https:\/\/www.bontempi.it\/fr\/wp-json\/wp\/v2\/media\/46417"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bontempi.it\/fr\/wp-json\/wp\/v2\/media\/162128"}],"wp:attachment":[{"href":"https:\/\/www.bontempi.it\/fr\/wp-json\/wp\/v2\/media?parent=125597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}