{"id":161807,"date":"2026-03-20T14:12:20","date_gmt":"2026-03-20T13:12:20","guid":{"rendered":"https:\/\/www.bontempi.it\/?post_type=designer&#038;p=161807"},"modified":"2026-03-20T14:16:31","modified_gmt":"2026-03-20T13:16:31","slug":"giorgio-manzali","status":"publish","type":"designer","link":"https:\/\/www.bontempi.it\/de\/designer\/giorgio-manzali\/","title":{"rendered":"Giorgio Manzali"},"content":{"rendered":"<p class=\"p1\">Giorgio Manzali hat eine Ausbildung in Bildhauerei, Malerei und Szenografie, die er im Laufe der Zeit zu einer einheitlichen Ausdruckssprache verbunden hat.<\/p>\n<p class=\"p1\">Seit 1980 richtete er einen Teil seiner Arbeit zun\u00e4chst auf die Architektur und sp\u00e4ter auf das Design aus, ausgehend von der \u00dcberzeugung, dass ein Gem\u00e4lde oder eine Skulptur aus einem Entwurf entsteht \u2013 ebenso wie ein Haus, ein Sofa, ein Tisch oder eine Lampe.<\/p>\n<p class=\"p1\">In dieser Sichtweise kann die Gesamtheit von Objekten und R\u00e4umen als eine Komposition aus Form und Farbe verstanden werden \u2013 ein \u00dcbergang vom Irrationalen zum Rationalen: Elemente, mit denen der Mensch in engem Kontakt lebt und die ihn letztlich immer widerspiegeln.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Giorgio Manzali hat eine Ausbildung in Bildhauerei, Malerei und Szenografie, die er im Laufe der Zeit zu einer einheitlichen Ausdruckssprache verbunden hat. Seit 1980 richtete er einen Teil seiner Arbeit zun\u00e4chst auf die Architektur und sp\u00e4ter auf das Design aus, ausgehend von der \u00dcberzeugung, dass ein Gem\u00e4lde oder eine Skulptur aus einem Entwurf entsteht \u2013 [&hellip;]<\/p>\n","protected":false},"featured_media":161802,"template":"","class_list":["post-161807","designer","type-designer","status-publish","has-post-thumbnail","hentry"],"acf":{"gallery":""},"_links":{"self":[{"href":"https:\/\/www.bontempi.it\/de\/wp-json\/wp\/v2\/designer\/161807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bontempi.it\/de\/wp-json\/wp\/v2\/designer"}],"about":[{"href":"https:\/\/www.bontempi.it\/de\/wp-json\/wp\/v2\/types\/designer"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bontempi.it\/de\/wp-json\/wp\/v2\/media\/161802"}],"wp:attachment":[{"href":"https:\/\/www.bontempi.it\/de\/wp-json\/wp\/v2\/media?parent=161807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}